﻿{"id":5032,"date":"2016-05-04T14:59:35","date_gmt":"2016-05-04T12:59:35","guid":{"rendered":"http:\/\/www.lilec.it\/romanticismo\/?post_type=tribe_events&#038;p=5032"},"modified":"2016-05-30T10:44:38","modified_gmt":"2016-05-30T08:44:38","slug":"una-nuova-grammatica-amorosa-i-personaggi-femminili-di-catherine-dunne","status":"publish","type":"tribe_events","link":"https:\/\/www.lilec.it\/romanticismo\/event\/una-nuova-grammatica-amorosa-i-personaggi-femminili-di-catherine-dunne\/","title":{"rendered":"Una nuova grammatica amorosa. I personaggi femminili di Catherine Dunne"},"content":{"rendered":"<p>Una lectio magistralis dalla <em>Casa delle donne di Bologna<br \/>\n<\/em>in occasione della X Edizione del Festival<em> La Violenza Illustrata <\/em>(Bologna, 10-29 novembre 2015)<br \/>\nin collaborazione con <em>Associazione Orlando e Biblioteca Italiana delle Donne<\/em><\/p>\n<p><a href=\"https:\/\/euc-word-view.officeapps.live.com\/wv\/WordViewer\/request.pdf?WOPIsrc=https%3A%2F%2Foutlook%2Eoffice365%2Ecom%3A443%2Fowa%2F20646ad1%2D97df%2D4c9c%2D8ccf%2D6d5b91640158%2540studio%2Eunibo%2Eit%2Fwopi%2Ffiles%2F%40%2Fowaatt%3Fowaatt%3DMVMtMS01LTIxLTE1NTI4MTk4NzQtODkxMDk0OTU3LTMyNTY5MzQzMDQtNDA3NDMyNDI0UAxVInTTCAEBAQAA&amp;access_token=eyJ0eXAiOiJKV1QiLCJhbGciOiJSUzI1NiIsIng1dCI6IkkzTDVfM3pTRVZPT3RmQmZFTGpXRmMwaFNwWSJ9%2EeyJpc3MiOiIwMDAwMDAwMi0wMDAwLTBmZjEtY2UwMC0wMDAwMDAwMDAwMDBAZTk5NjQ3ZGMtMWIwOC00NTRhLWJmOGMtNjk5MTgxYjM4OWFiIiwiYXVkIjoiMDAwMDAwMDItMDAwMC0wZmYxLWNlMDAtMDAwMDAwMDAwMDAwL291dGxvb2sub2ZmaWNlMzY1LmNvbUBlOTk2NDdkYy0xYjA4LTQ1NGEtYmY4Yy02OTkxODFiMzg5YWIiLCJuYmYiOjE0NjIzNjk1MTksImV4cCI6MTQ2MjQ1NTkxOSwidmVyIjoiRXhjaGFuZ2UuQ2FsbGJhY2suVjEiLCJhcHBjdHhzZW5kZXIiOiJPd2FXYWNAZTk5NjQ3ZGMtMWIwOC00NTRhLWJmOGMtNjk5MTgxYjM4OWFiIiwiYXBwY3R4Ijoie1wic210cFwiOlwibGF1cmEubWNjYXJ0aHlAc3R1ZGlvLnVuaWJvLml0XCIsXCJzY29wZVwiOlwiQUFNa0FESXdOalEyWVdReExUazNaR1l0TkdNNVl5MDRZMk5tTFRaa05XSTVNVFkwTURFMU9BQkdBQUFBQUFDUWwyTXRhRUkwVG9mbmczVjRiUVBGQndCZXZqakdSZEU3UzZwVXBla0FLZFVCQUFBQUFBRU1BQUJldmpqR1JkRTdTNnBVcGVrQUtkVUJBQURHTUNnZkFBQUJFZ0FRQURvYlJTcjZKVGxJZyt2YWdTVnpOc1E9XCIsXCJtc2V4Y2hwcm90XCI6XCJvd2FcIn0ifQ%2EcKZMYXAmakIjtLdprCClIfK1Mys5TTnT4gIJwHpVNr9443U%2DMXQBp%2D2OF0QukVEbHpYB%5F96hPlkxUoCPIj0gkx5OT%2DmTYG%2Dibjxuzxu33fIYSaOhg7eMSwuwBi2hGdjYzW4BdKo5bhJh7R3cYockJvdyDZUoh6lqZk3WhrDbFbe76eGiiPP1vGo9TMcrNuZ9T%5FPYY5vtq06MnrMtjLz6hXkp86QYs10BsLyoruS5DB%5FNrVLVv4UmhTuLBxkLcIm8etXIZ1rwbSLth5jcZCnr0R9X%2Djh8ptr%2DHB8bu%5FipBoZwEERxkjWjv3ugCh0lIWzQ5SHGWjemr5CCyCNT2YJsYg&amp;access_token_ttl=0&amp;z=mACMX5DrfHi%2BHq7gH8wzybs9KrJwJ%2FfIsmHkAy%2FXt1Q%3D&amp;type=accesspdf&amp;usid=7acbb5ab-076e-470e-a392-e5b330ab1396&amp;build=16.0.6921.2200&amp;waccluster=AM3\">Locandina<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una lectio magistralis dalla Casa delle donne di Bologna in occasione della X Edizione del Festival La Violenza Illustrata (Bologna, 10-29 novembre 2015) in collaborazione con Associazione Orlando e Biblioteca Italiana delle Donne Locandina<\/p>\n","protected":false},"author":101012,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":""},"tags":[],"tribe_events_cat":[35],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una nuova grammatica amorosa. I personaggi femminili di Catherine Dunne - Centro Interuniversitario per lo Studio del Romanticismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lilec.it\/romanticismo\/event\/una-nuova-grammatica-amorosa-i-personaggi-femminili-di-catherine-dunne\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una nuova grammatica amorosa. I personaggi femminili di Catherine Dunne - Centro Interuniversitario per lo Studio del Romanticismo\" \/>\n<meta property=\"og:description\" content=\"Una lectio magistralis dalla Casa delle donne di Bologna in occasione della X Edizione del Festival La Violenza Illustrata (Bologna, 10-29 novembre 2015) in collaborazione con Associazione Orlando e Biblioteca Italiana delle Donne Locandina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lilec.it\/romanticismo\/event\/una-nuova-grammatica-amorosa-i-personaggi-femminili-di-catherine-dunne\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Interuniversitario per lo Studio del Romanticismo\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-30T08:44:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lilec.it\/romanticismo\/event\/una-nuova-grammatica-amorosa-i-personaggi-femminili-di-catherine-dunne\/\",\"url\":\"https:\/\/www.lilec.it\/romanticismo\/event\/una-nuova-grammatica-amorosa-i-personaggi-femminili-di-catherine-dunne\/\",\"name\":\"Una nuova grammatica amorosa. I personaggi femminili di Catherine Dunne - Centro Interuniversitario per lo Studio del Romanticismo\",\"isPartOf\":{\"@id\":\"https:\/\/www.lilec.it\/romanticismo\/#website\"},\"datePublished\":\"2016-05-04T12:59:35+00:00\",\"dateModified\":\"2016-05-30T08:44:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lilec.it\/romanticismo\/event\/una-nuova-grammatica-amorosa-i-personaggi-femminili-di-catherine-dunne\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lilec.it\/romanticismo\/event\/una-nuova-grammatica-amorosa-i-personaggi-femminili-di-catherine-dunne\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lilec.it\/romanticismo\/event\/una-nuova-grammatica-amorosa-i-personaggi-femminili-di-catherine-dunne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.lilec.it\/romanticismo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi\",\"item\":\"https:\/\/www.lilec.it\/romanticismo\/events\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Una nuova grammatica amorosa. I personaggi femminili di Catherine Dunne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lilec.it\/romanticismo\/#website\",\"url\":\"https:\/\/www.lilec.it\/romanticismo\/\",\"name\":\"Centro Interuniversitario per lo Studio del Romanticismo\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lilec.it\/romanticismo\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una nuova grammatica amorosa. I personaggi femminili di Catherine Dunne - Centro Interuniversitario per lo Studio del Romanticismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lilec.it\/romanticismo\/event\/una-nuova-grammatica-amorosa-i-personaggi-femminili-di-catherine-dunne\/","og_locale":"it_IT","og_type":"article","og_title":"Una nuova grammatica amorosa. I personaggi femminili di Catherine Dunne - Centro Interuniversitario per lo Studio del Romanticismo","og_description":"Una lectio magistralis dalla Casa delle donne di Bologna in occasione della X Edizione del Festival La Violenza Illustrata (Bologna, 10-29 novembre 2015) in collaborazione con Associazione Orlando e Biblioteca Italiana delle Donne Locandina","og_url":"https:\/\/www.lilec.it\/romanticismo\/event\/una-nuova-grammatica-amorosa-i-personaggi-femminili-di-catherine-dunne\/","og_site_name":"Centro Interuniversitario per lo Studio del Romanticismo","article_modified_time":"2016-05-30T08:44:38+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lilec.it\/romanticismo\/event\/una-nuova-grammatica-amorosa-i-personaggi-femminili-di-catherine-dunne\/","url":"https:\/\/www.lilec.it\/romanticismo\/event\/una-nuova-grammatica-amorosa-i-personaggi-femminili-di-catherine-dunne\/","name":"Una nuova grammatica amorosa. I personaggi femminili di Catherine Dunne - Centro Interuniversitario per lo Studio del Romanticismo","isPartOf":{"@id":"https:\/\/www.lilec.it\/romanticismo\/#website"},"datePublished":"2016-05-04T12:59:35+00:00","dateModified":"2016-05-30T08:44:38+00:00","breadcrumb":{"@id":"https:\/\/www.lilec.it\/romanticismo\/event\/una-nuova-grammatica-amorosa-i-personaggi-femminili-di-catherine-dunne\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lilec.it\/romanticismo\/event\/una-nuova-grammatica-amorosa-i-personaggi-femminili-di-catherine-dunne\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lilec.it\/romanticismo\/event\/una-nuova-grammatica-amorosa-i-personaggi-femminili-di-catherine-dunne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lilec.it\/romanticismo\/"},{"@type":"ListItem","position":2,"name":"Eventi","item":"https:\/\/www.lilec.it\/romanticismo\/events\/"},{"@type":"ListItem","position":3,"name":"Una nuova grammatica amorosa. I personaggi femminili di Catherine Dunne"}]},{"@type":"WebSite","@id":"https:\/\/www.lilec.it\/romanticismo\/#website","url":"https:\/\/www.lilec.it\/romanticismo\/","name":"Centro Interuniversitario per lo Studio del Romanticismo","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lilec.it\/romanticismo\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.lilec.it\/romanticismo\/wp-json\/wp\/v2\/tribe_events\/5032"}],"collection":[{"href":"https:\/\/www.lilec.it\/romanticismo\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.lilec.it\/romanticismo\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.lilec.it\/romanticismo\/wp-json\/wp\/v2\/users\/101012"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lilec.it\/romanticismo\/wp-json\/wp\/v2\/comments?post=5032"}],"version-history":[{"count":0,"href":"https:\/\/www.lilec.it\/romanticismo\/wp-json\/wp\/v2\/tribe_events\/5032\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lilec.it\/romanticismo\/wp-json\/wp\/v2\/media?parent=5032"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lilec.it\/romanticismo\/wp-json\/wp\/v2\/tags?post=5032"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.lilec.it\/romanticismo\/wp-json\/wp\/v2\/tribe_events_cat?post=5032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}